{"id":1599,"date":"2025-06-25T02:31:00","date_gmt":"2025-06-25T00:31:00","guid":{"rendered":"https:\/\/escrebieux-environnement.fr\/site\/?p=1599"},"modified":"2025-06-23T06:32:57","modified_gmt":"2025-06-23T04:32:57","slug":"la-fee-electricite-a-perdu-sa-baguette","status":"publish","type":"post","link":"https:\/\/escrebieux-environnement.fr\/site\/la-fee-electricite-a-perdu-sa-baguette\/","title":{"rendered":"La f\u00e9e \u00e9lectricit\u00e9 a perdu sa baguette"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quel rapport peut-il y avoir entre le black-out \u00e9lectrique en Espagne et en partie au Portugal, les sabotages de lignes haute tension et de postes de transformation qui ont plong\u00e9 Cannes et Nice dans le noir, l\u2019alerte du PDG d\u2019EDF vir\u00e9 par Macron sur le d\u00e9fi que devra relever l\u2019entreprise : la surproduction d\u2019\u00e9lectricit\u00e9 ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tous ces \u00e9v\u00e8nements r\u00e9v\u00e8lent l\u2019aveuglement des d\u00e9cideurs et l\u2019absence d\u2019anticipation, bloqu\u00e9s qu\u2019ils sont dans leur r\u00e9flexion par la croyance dans la croissance et le techno solutionisme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La constitution du r\u00e9seau \u00e9lectrique s\u2019est faite sur le gigantisme. Maillage du territoire fran\u00e7ais \u00e0 coup de lignes THT (tr\u00e8s haute tension) \u00e9tendu ensuite \u00e0 l\u2019Europe, de la Finlande \u00e0 l\u2019Espagne, sans r\u00e9flexion sur des solutions techniques diff\u00e9rentes, comme inciter \u00e0 l\u2019autonomie de petits territoires avec des possibilit\u00e9s de solidarit\u00e9 avec les voisins si besoin.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce choix \u00e9tait bien entendu li\u00e9 au moyen de production ; les centrales nucl\u00e9aires mais aussi les grosses centrales \u00e0 charbon ou \u00e0 gaz induisaient ce type de distribution. On aurait pu penser que la bifurcation vers les \u00e9nergies renouvelables allait changer la donne, qu\u2019on allait produire et distribuer de fa\u00e7on d\u00e9centralis\u00e9e. Pas du tout.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainsi RTE (R\u00e9seau de Transport d\u2019\u00c9lectricit\u00e9) investit pour la seule Occitanie 712 millions d\u2019euros dans le raccordement des \u00e9nergies renouvelables au r\u00e9seau global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces investissements justifient \u00e9videmment l\u2019installation de toujours plus d\u2019\u00e9oliennes et de photovolta\u00efque alors m\u00eame que RTE pointe dans ses rapports sur la production et la consommation d\u2019\u00e9lectricit\u00e9 en France que cette derni\u00e8re est au m\u00eame niveau qu\u2019en 2005, alors que la production ne cesse d\u2019augmenter.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non seulement les installations d\u2019ENR se multiplient mais les soucis de maintenance des centrales nucl\u00e9aires sont pass\u00e9s et elles retrouvent leur niveau de production ; enfin l\u2019EPR de Flamanville commence \u00e0 monter en charge.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ce contexte EDF arrive \u00e0 caser son \u00e9lectricit\u00e9 \u00e0 l\u2019export mais les jours o\u00f9 elle la vend \u00e0 un co\u00fbt n\u00e9gatif (c\u2019est \u00e0 dire o\u00f9 elle paye pour qu\u2019on la lui prenne) augmentent.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainsi en mars RTE a vers\u00e9 pr\u00e8s de 12 000 euros par MWh aux pays voisins pour qu\u2019ils prennent l\u2019\u00e9lectricit\u00e9 exc\u00e9dentaire. En outre le r\u00e9seau a \u00e9t\u00e9 oblig\u00e9 de d\u00e9dommager les promoteurs d\u2019ENR pour qu\u2019ils ne produisent pas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Donc on subventionne la production en payant l\u2019\u00e9lectricit\u00e9 issue des ENR plus cher que le prix du march\u00e9 et on paye \u00e0 nouveau pour stopper la production. Dans ce secteur pile tu gagnes, face pareil&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Devant cette r\u00e9alit\u00e9 \u2013 o\u00f9 l\u2019on produit trop et on continue \u00e0 accroitre les moyens de production malgr\u00e9 leurs atteintes \u00e0 la biodiversit\u00e9 et l\u2019artificialisation des sols \u2013 les d\u00e9cideurs se retranchent derri\u00e8re une hypoth\u00e8se : demain on consommera beaucoup plus donc il faut pr\u00e9voir.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quels seront les relais de consommation esp\u00e9r\u00e9s : la voiture \u00e9lectrique, l\u2019\u00e9lectrification de certaines production industrielles (acier, b\u00e9ton\u2026) les data centers n\u00e9cessaires entre autres pour le d\u00e9veloppement de l\u2019Intelligence Artificielle&nbsp;?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais cela ne se passe pas comme pr\u00e9vu. Les ventes de v\u00e9hicules \u00e9lectriques stagnent et les industriels demandent toujours plus d\u2019aides pour passer \u00e0 l\u2019\u00e9lectricit\u00e9 et trainent des pieds. On essaie bien de relancer la consommation en limitant les aides \u00e0 la r\u00e9novation de l\u2019habitat ou en assouplissant l\u2019interdiction de louer des passoires thermiques mais \u00e7a ne suffit pas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons donc surproduction, ce qui, il faut le rappeler, peut d\u00e9stabiliser totalement le r\u00e9seau, qui par ailleurs du fait de son gigantisme est de plus en plus vuln\u00e9rable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le r\u00e9sultat&nbsp;: un PDG d\u2019EDF qui alerte sur cette surproduction au moment o\u00f9 il quitte son poste comme s\u2019il n\u2019y avait pas contribu\u00e9 durant son mandat&nbsp;; une \u00e9norme panne dans la p\u00e9ninsule ib\u00e9rique qui reste \u00e0 ce jour inexpliqu\u00e9e et un petit groupe d\u2019activistes qui, avec des moyens certainement d\u00e9risoires, plonge des centaines de milliers d\u2019habitants dans le noir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le black-out est certainement de ces trois faits, et celui qui devrait le plus nous inqui\u00e9ter : car soit la cause est volontairement cach\u00e9e, soit, et c\u2019est nettement plus grave, il n\u2019y a pas d\u2019explication donc pas de rem\u00e8de ni de parade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">toutesnosenergies.fr<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quel rapport peut-il y avoir entre le black-out \u00e9lectrique en Espagne et en partie au Portugal, les sabotages de lignes haute tension et de postes de transformation qui ont plong\u00e9 Cannes et Nice dans le noir, l\u2019alerte du PDG d\u2019EDF vir\u00e9 par Macron sur le d\u00e9fi que devra relever l\u2019entreprise : la surproduction d\u2019\u00e9lectricit\u00e9 ? [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1599","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts\/1599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/comments?post=1599"}],"version-history":[{"count":1,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts\/1599\/revisions"}],"predecessor-version":[{"id":1600,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts\/1599\/revisions\/1600"}],"wp:attachment":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/media?parent=1599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/categories?post=1599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/tags?post=1599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}