{"id":1848,"date":"2025-12-04T02:39:00","date_gmt":"2025-12-04T01:39:00","guid":{"rendered":"https:\/\/escrebieux-environnement.fr\/site\/?p=1848"},"modified":"2025-12-03T15:48:28","modified_gmt":"2025-12-03T14:48:28","slug":"le-point-sur-le-dossier-escrebieux","status":"publish","type":"post","link":"https:\/\/escrebieux-environnement.fr\/site\/le-point-sur-le-dossier-escrebieux\/","title":{"rendered":"Le point sur le dossier ESCREBIEUX"},"content":{"rendered":"\n<p class=\"has-xx-large-font-size wp-block-paragraph\"><strong>Le travail ne manque pas.<\/strong><\/p>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\"><strong>Il y a d\u00e9j\u00e0 des certitudes sur ce que l\u2019on entreprend pour transmettre \u00e0 la Cour administrative d\u2019appel de Douai avant le 28 d\u00e9cembre.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons bien avanc\u00e9 lors de la r\u00e9union en date du 2 d\u00e9cembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous pouvons d\u00e9j\u00e0 compter sur l\u2019intervention de plusieurs personnes, habitant ou Bois-Bernard ou Drocourt ou Izel ou Qui\u00e9ry. Il est certain qu\u2019il y aura plus de personnes qui d\u00e9fendront leur territoire. parce que directement impact\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Au niveau des communes<\/strong>, nous pouvions d\u00e9j\u00e0 compter sur l\u2019appui des communes de Bois-Bernard, Neuvireuil et Qui\u00e9ry.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une nouvelle commune est venue r\u00e9cemment en soutien&nbsp;: Brebi\u00e8res. Le conseil municipal a d\u00e9cid\u00e9, lors de la s\u00e9ance du 19 novembre, ce qui suit&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00ab&nbsp;<em>ARTICLE 1 :<\/em><\/strong><em> \u2026 <\/em><em>apporter le soutien officiel de la commune de BREBIERES \u00e0 l\u2019Association de l\u2019Escrebieux dans ses actions visant \u00e0 assurer une expertise compl\u00e8te et ind\u00e9pendante sur les impacts du projet de parc \u00e9olien.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>ARTICLE 2 :<\/em><\/strong><em> \u2026<\/em><em> mandater le Maire pour repr\u00e9senter la commune dans toute d\u00e9marche, r\u00e9union ou consultation relative au projet.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>ARTICLE 3 :<\/em><\/strong><em> \u2026 autoriser le Maire \u00e0 \u00e9tablir, si n\u00e9cessaire, toute convention de coop\u00e9ration avec l\u2019association pour favoriser l\u2019\u00e9change d\u2019informations, la d\u00e9fense de l\u2019environnement et la pr\u00e9servation du cadre de vie des habitants.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, Drocourt n\u2019a pas encore r\u00e9uni son Conseil municipal pour d\u00e9lib\u00e9rer sur la question pos\u00e9e par l\u2019implantation des \u00e9oliennes dans la vall\u00e9e de l\u2019Escrebieux. Pour rappel, l\u2019une des deux possibles \u00e9oliennes situ\u00e9e sur le territoire d\u2019Izel est tr\u00e8s proche d\u2019habitations drocourtoises, notamment \u00e0 l\u2019extr\u00e9mit\u00e9 de la rue de Qui\u00e9ry. Nous sommes tr\u00e8s confiants \u00e0 propos de ce soutien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, les communes suivantes n\u2019iront pas en justice mais soutiennent le refus d\u2019implantation sur Izel et Qui\u00e9ry\u00a0: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fresnes-les-Montauban, Fresnoy, H\u00e9nin-Beaumont, Rouvroy, Sailly-en-Ostrevent et Vitry-en-Artois. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cela signifie que toutes les communes du Pas-de-Calais entourant le projet \u2013 et m\u00eame un peu plus &#8211; sont oppos\u00e9es \u00e0 ces \u00e9oliennes industrielles.<br>Bien s\u00fbr, il y a une exception \u2026 et de taille\u00a0: Izel, concern\u00e9e par deux \u00e9ventuelles \u00e9oliennes. Il faut rappeler ce qui a \u00e9t\u00e9 \u00e9crit dans <em>La voix du Nord<\/em> :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab&nbsp;Izel-l\u00e8s-Equerchin \u2026 est favorable au projet, \u00ab&nbsp;sur la continuit\u00e9 de<em> mon pr\u00e9d\u00e9cesseur.&nbsp; Les d\u00e9tracteurs d\u00e9noncent une pollution visuelle , mais quand on vient de Fresnes, on voit des lignes \u00e9lectriques, des \u00e9oliennes (\u00e0 Courcelles-les-Lens-Flers-Esquerchin), le champ visuel est d\u00e9j\u00e0 d\u00e9t\u00e9rior\u00e9, cela ne change pas grand-chose&nbsp;\u00bb<\/em>, explique la maire Corinne DUBOIS.&nbsp;\u00bb Le raisonnement de la maire d&rsquo;Izel est classique et utilis\u00e9 encore par le rapporteur de la Cour administrative d\u2019appel de Douai lors de l\u2019audience ayant trait\u00e9 le projet d\u2019\u00e9oliennes sur la commune de Brebi\u00e8res : <em>la r\u00e9gion est d\u00e9j\u00e0 pollu\u00e9e (anthropis\u00e9e, comme on dit dans le beau jargon), donc une pollution de plus peut s&rsquo;envisager<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du c\u00f4t\u00e9 des associations, nous attendons avec optimisme la position de trois d\u2019entre elles. Nous pensons qu\u2019elles seront de la partie pour aller en justice avec nous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, il est \u00e9vident que l\u2019association ESCREBIEUX ira en justice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout est fait pour finaliser, durant le court laps de temps qui nous reste, le dossier qui sera mis entre les mains de la Cour administrative de Douai.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">** **<\/p>\n\n\n\n<p class=\"has-xx-large-font-size wp-block-paragraph\"><strong>Pour raconter l\u2019histoire autrement<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons en t\u00eate la victoire de l\u2019association ASPECT qui a men\u00e9 une bataille victorieuse contre Engie dans la r\u00e9gion de Dury, Eterpigny et R\u00e9court. Cette association a gagn\u00e9 notamment parce qu\u2019il y avait un monument historique \u00e0 L\u00e9cluse, \u00e0 c\u00f4t\u00e9 de ces trois communes. Engie a mordu la poussi\u00e8re en Cour administrative \u00e0 Douai, puis en Conseil d\u2019\u00c9tat. Nous avons le soutien de cette association \u2013 pas seulement en paroles&nbsp;&#8211;&nbsp;; nous esp\u00e9rons aboutir au m\u00eame r\u00e9sultat&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci \u00e0 toutes les personnes qui vont aller en justice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci \u00e0 toutes les communes qui nous soutiennent de diff\u00e9rentes fa\u00e7ons.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci aux associations qui sont d\u00e9j\u00e0 d\u00e9bord\u00e9es mais prennent le temps de venir s\u2019occuper de ce probl\u00e8me.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout ce qui se fait profite de la haute comp\u00e9tence, de l\u2019exp\u00e9rience et de la t\u00e9nacit\u00e9 de plusieurs personnes \u2013 dans diff\u00e9rents domaines &#8211; qui sont adh\u00e9rentes ou\/et se sont associ\u00e9es \u00e0 l\u2019association, de fa\u00e7on b\u00e9n\u00e9vole\u00a0; sans ce travail, nous aurions eu beaucoup  de peine pour argumenter un dossier tellement complexe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout cet ensemble montre qu\u2019il y a beaucoup de soutiens &#8211; individuels et collectifs &#8211;  parce que le sujet est important. Cela nous rassure. Cela ne veut pas dire que nous sommes s\u00fbrs de gagner, mais cet optimisme que l\u2019on d\u00e9veloppe doit nous permettre d\u2019aller tr\u00e8s loin et d\u2019envisager sereinement une victoire \u00e0 la fin de toutes ces activit\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout ce travail pour aller en justice et informer ne doit pas faire oublier non plus que plusieurs personnes de l\u2019association se d\u00e9m\u00e8nent pour faire connaitre tout ce qui se pr\u00e9pare. Tout ceci ne peut se faire que s\u2019il y a un appui important des habitants des communes cit\u00e9es\u2026 ou d\u2019ailleurs&nbsp;! C\u2019est d\u00e9j\u00e0 lanc\u00e9, il faut le continuer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comment aider&nbsp;?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>en distribuant des tracts, en mettant des affiches sur le devant ou dans les maisons, en informant, \u2026<\/li>\n\n\n\n<li>en participant \u00e0 l\u2019aide financi\u00e8re \u2013 secteur tellement important\u00a0; c\u2019est-\u00e0-dire en faisant un don et\/ou en adh\u00e9rant \u00e0 l\u2019association ESCREBIEUX<\/li>\n\n\n\n<li>en commen\u00e7ant ou en continuant \u00e0 faire de la publicit\u00e9 pour le loto organis\u00e9 par l\u2019association, qui aura lieu le dimanche 1<sup>er<\/sup> f\u00e9vrier 2026 \u00e0 la salle Jacques Brel de Qui\u00e9ry-la-Motte<\/li>\n\n\n\n<li>\u00a0\u2026<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le travail ne manque pas. Il y a d\u00e9j\u00e0 des certitudes sur ce que l\u2019on entreprend pour transmettre \u00e0 la Cour administrative d\u2019appel de Douai avant le 28 d\u00e9cembre. Nous avons bien avanc\u00e9 lors de la r\u00e9union en date du 2 d\u00e9cembre. Nous pouvons d\u00e9j\u00e0 compter sur l\u2019intervention de plusieurs personnes, habitant ou Bois-Bernard ou [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1848","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts\/1848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/comments?post=1848"}],"version-history":[{"count":2,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts\/1848\/revisions"}],"predecessor-version":[{"id":1850,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts\/1848\/revisions\/1850"}],"wp:attachment":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/media?parent=1848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/categories?post=1848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/tags?post=1848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}