{"id":192,"date":"2022-10-12T09:40:00","date_gmt":"2022-10-12T07:40:00","guid":{"rendered":"https:\/\/escrebieux-environnement.fr\/site\/?p=192"},"modified":"2022-10-12T09:42:53","modified_gmt":"2022-10-12T07:42:53","slug":"la-bataille-a-propos-des-eoliennes-a-commence","status":"publish","type":"post","link":"https:\/\/escrebieux-environnement.fr\/site\/la-bataille-a-propos-des-eoliennes-a-commence\/","title":{"rendered":"La bataille des \u00e9oliennes a commenc\u00e9"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\">Intervent -le promoteur du projet de 3 \u00e9oliennes INDUSTRIELLES dans la Vall\u00e9e de l\u2019Escrebieux- a tir\u00e9 le premier. Il fait ce que bon lui semble\u2026 pour l\u2019instant.<br><strong>L\u2019enqu\u00eate publique aura lieu du 7 novembre au 7 d\u00e9cembre alors qu\u2019elle \u00e9tait pr\u00e9vue en mars 2023.<br>Il faut donc aller vite si l\u2019on veut montrer notre opposition \u00e0 ces installations. Et le faire savoir en masse. Notamment en allant \u00e9crire quelque chose dans le registre de l\u2019enqu\u00eate publique&nbsp;; MAIS PAS QUE&nbsp;!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il faut rappeler que au moins 75&nbsp;% des Izellois.es et Qui\u00e9rysien.nes sont oppos\u00e9.es \u00e0 ce projet d\u2019\u00e9oliennes INDUSTRIELLES.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Il faut aussi le faire savoir \u00e0 l\u2019occasion de l\u2019enqu\u00eate publique. Mais Intervent se moque pas mal de ces oppositions classiques. Souvenez-vous de l\u2019opposition au renforcement de la ligne THT (Tr\u00e8s Haute Tension) entre Gavrelle et Avelin \u2026 ligne qui passe tr\u00e8s pr\u00e8s de chez nous. Il y avait une tr\u00e8s forte opposition. Cela n\u2019a pas suffi&nbsp;: RTE s\u2019en est moqu\u00e9 et a fait ce que cette entreprise voulait faire&nbsp;: elle a promis beaucoup de choses mais ne s\u2019en souvient plus ! <\/p>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\"><strong>Donc, pour gagner, il faut aller plus loin dans l\u2019opposition.<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Le sondage \u00e0 Izel et Qui\u00e9ry a donc montr\u00e9 que nous sommes oppos\u00e9s \u00e0 ces \u00e9oliennes INDUSTRIELLES&nbsp;; l\u2019enqu\u00eate publique doit confirmer notre opposition. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais, avec des entreprises pareils -qui n\u2019h\u00e9sitent pas aussi \u00e0 passer outre aux r\u00e8gles d\u00e9cid\u00e9es-, il faudra continuer \u00e0 mener des actions \u2026 apr\u00e8s le 7 d\u00e9cembre. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le combat ne fait que commencer. C\u2019est cela que l\u2019on \u00e9tudiera notamment lors de l\u2019AG du 29 octobre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des informations passeront par le site de l\u2019association&nbsp;; mais pas que&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous \u00eates donc pri\u00e9s de visiter r\u00e9guli\u00e8rement le site ou de nous contacter en apportant votre contribution&nbsp;: vos id\u00e9es permettront de voir plus clair dans ce que l\u2019on pourra faire pour l\u2019objectif final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contacts possibles : <strong>voir la page \u00ab\u00a0CONTACT\u00a0\u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Derni\u00e8re nouvelle annonc\u00e9 par la mairie de Qui\u00e9ry au sujet de l&rsquo;enqu\u00eate publique<\/h2>\n\n\n\n<p class=\"has-vivid-red-color has-light-green-cyan-background-color has-text-color has-background has-large-font-size wp-block-paragraph\">Le dossier sera consultable en mairie <strong>en dehors des heures d\u2019ouverture au public uniquement<\/strong> sur rendez vous et dans le respect des heures de pr\u00e9sence de la secr\u00e9taire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elle ne s&rsquo;arr\u00eatera pas le 8 d\u00e9cembre !<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-192","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts\/192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/comments?post=192"}],"version-history":[{"count":9,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts\/192\/revisions"}],"predecessor-version":[{"id":208,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/posts\/192\/revisions\/208"}],"wp:attachment":[{"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/media?parent=192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/categories?post=192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escrebieux-environnement.fr\/site\/wp-json\/wp\/v2\/tags?post=192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}